{"id":124142,"date":"2021-02-06T18:54:32","date_gmt":"2021-02-06T18:54:32","guid":{"rendered":"https:\/\/arredareidee.com\/?post_type=product&#038;p=124142"},"modified":"2021-08-13T08:25:14","modified_gmt":"2021-08-13T08:25:14","slug":"pannelli-decorativi-3d-jungle","status":"publish","type":"product","link":"https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/","title":{"rendered":"Pannelli decorativi 3D JUNGLE"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"margin-bottom: .0001pt; line-height: normal;\"><span style=\"font-size: 12.0pt; font-family: 'Georgia','serif';\"><strong>PANNELLI DECORATIVI 3D<\/strong>, COMPOSIZIONE IN <strong>GERICE<\/strong> (GESSO RINFORZATO CERAMICO) <\/span><b><span style=\"font-size: 14.0pt; font-family: 'Georgia','serif';\">PER INTERNI<\/span><\/b><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: .0001pt; line-height: normal;\"><span style=\"font-size: 12.0pt; font-family: 'Georgia','serif';\">E\u2019 un materiale eco compatibile innovativo, studiato appositamente dall\u2019azienda a base di gesso ceramico fibrorinforzato.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: .0001pt; line-height: normal;\"><span style=\"font-size: 12.0pt; font-family: 'Georgia','serif';\">Per l\u2019utilizzo: Adagiamo\u00a0 i pannelli 3D in GERICE facendoli aderire alla parete con lo speciale COLLSTUK prodotto da Decor, stuccando le giunture con lo stesso (avendo la doppia valenza di collante e finitura) per un risultato perfetto. Successivamente, si dipingono con qualsiasi pittura a base acqua, trattandoli anticipatamente con specifico fissativo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"line-height: normal;\"><span style=\"font-size: 12.0pt; font-family: 'Georgia','serif';\">COMPOSIZIONE IN <strong>MANOCER<\/strong> (MALTA NOBILE CERAMIZZATA)\u00a0<\/span><b><span style=\"font-size: 14.0pt; font-family: 'Georgia','serif';\">PER ESTERNI E INTERNI<\/span><\/b><\/p>\n<p class=\"MsoNormal\" style=\"line-height: normal;\"><span style=\"font-size: 12.0pt; font-family: 'Times New Roman','serif';\">E\u2019 un impasto fibrorinforzato a base di malta nobile ceramizzata frutto della ventennale esperienza di ricerca dell\u2019azienda stessa costituito da materiale naturale quale la pietra e da altri ingredienti di origine naturale miscelati con maestria, eco-compatibile e interamente riciclabile. Per l\u2019utilizzo: Adagiamo i pannelli 3D in MANOCER facendoli aderire alla parete con l\u2019apposito collante a base cementizia ad alte prestazioni con scivolamento verticale nullo (Classe C2TE). Ad asciugatura avvenuta, si prosegue con la stuccatura mediante l\u2019apposito stucco fornito sempre dall\u2019azienda stessa. Segue la carteggiatura e la tinteggiatura con qualsiasi tipo di pittura, trattandoli anticipatamente con specifico fissativo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Dimensioni: 50 x 50 x 3<\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Peso GERICE: Kg. 6,3<\/strong><\/span><\/p>\n<p><strong><span style=\"font-size: 14pt;\">Peso MANOCER: Kg. 8,8<\/span><\/strong><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Collstuk <\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Consumo: 0,8 kg per elemento <\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><strong>Stucco <\/strong><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Consumo: 0,07 per elemento<\/span><\/p>\n<p><span style=\"font-size: 18pt;\"><strong>N.B. I pannelli sono forniti in colore NEUTRO<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tempi di consegna:<\/strong> Dopo la conferma dell\u2019ordine il tempo previsto per la produzione \u00e8 di 7 gg lavorativi prima della spedizione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-size: 14pt;\"><strong>Pannelli 3D modello Jungle<\/strong>, ispirato dalla selvaggia vegetazione della foresta tropicale.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Un intreccio di foglie che si sovrappongono l\u2019una sull\u2019altra creando un effetto tridimensionale e profondo.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Gli elementi che particolari sono le forme geometriche a rilievo che permettono di nascondere le fughe, creando un gioco di linee, avvolte continue e altre volte interrotte, che valorizza e personalizza la composizione.<\/span><\/p>\n<p><strong>TRASPORTO ZERO\u00a0<\/strong><\/p>\n","protected":false},"featured_media":124150,"template":"","meta":[],"product_brand":[],"product_cat":[109,30,22],"product_tag":[],"class_list":["post-124142","product","type-product","status-publish","has-post-thumbnail","product_cat-andrea-castrignano-pannelli-3d","product_cat-pannelli-3d","product_cat-pannelli-in-finta-pietra-ricostruita-naturale","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pannelli decorativi 3D JUNGLE per rivestimenti interni ed esterni<\/title>\n<meta name=\"description\" content=\"Pannelli decorativi 3D JUNGLE, sono realizzati con materiale eco compatibile innovativo, studiato appositamente dall\u2019azienda a base di\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pannelli decorativi 3D JUNGLE per rivestimenti interni ed esterni\" \/>\n<meta property=\"og:description\" content=\"Pannelli decorativi 3D JUNGLE, sono realizzati con materiale eco compatibile innovativo, studiato appositamente dall\u2019azienda a base di\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/\" \/>\n<meta property=\"og:site_name\" content=\"Arredareidee\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-13T08:25:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arredareidee.com\/wp-content\/uploads\/2021\/02\/Jungle-Decor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"533\" \/>\n\t<meta property=\"og:image:height\" content=\"687\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arredareidee.com\\\/index.php\\\/product\\\/pannelli-decorativi-3d-jungle\\\/\",\"url\":\"https:\\\/\\\/arredareidee.com\\\/index.php\\\/product\\\/pannelli-decorativi-3d-jungle\\\/\",\"name\":\"Pannelli decorativi 3D JUNGLE per rivestimenti interni ed esterni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arredareidee.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arredareidee.com\\\/index.php\\\/product\\\/pannelli-decorativi-3d-jungle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arredareidee.com\\\/index.php\\\/product\\\/pannelli-decorativi-3d-jungle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arredareidee.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Jungle-Decor.jpg\",\"datePublished\":\"2021-02-06T18:54:32+00:00\",\"dateModified\":\"2021-08-13T08:25:14+00:00\",\"description\":\"Pannelli decorativi 3D JUNGLE, sono realizzati con materiale eco compatibile innovativo, studiato appositamente dall\u2019azienda a base di\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arredareidee.com\\\/index.php\\\/product\\\/pannelli-decorativi-3d-jungle\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arredareidee.com\\\/index.php\\\/product\\\/pannelli-decorativi-3d-jungle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/arredareidee.com\\\/index.php\\\/product\\\/pannelli-decorativi-3d-jungle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arredareidee.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Jungle-Decor.jpg\",\"contentUrl\":\"https:\\\/\\\/arredareidee.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Jungle-Decor.jpg\",\"width\":533,\"height\":687,\"caption\":\"Jungle Decor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arredareidee.com\\\/index.php\\\/product\\\/pannelli-decorativi-3d-jungle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arredareidee.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/arredareidee.com\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pannelli decorativi 3D JUNGLE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arredareidee.com\\\/#website\",\"url\":\"https:\\\/\\\/arredareidee.com\\\/\",\"name\":\"Arredareidee\",\"description\":\"Decorazioni personalizzate\",\"publisher\":{\"@id\":\"https:\\\/\\\/arredareidee.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arredareidee.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arredareidee.com\\\/#organization\",\"name\":\"Arredareidee\",\"url\":\"https:\\\/\\\/arredareidee.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/arredareidee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arredareidee.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Arredareidee.png\",\"contentUrl\":\"https:\\\/\\\/arredareidee.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-Arredareidee.png\",\"width\":868,\"height\":157,\"caption\":\"Arredareidee\"},\"image\":{\"@id\":\"https:\\\/\\\/arredareidee.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pannelli decorativi 3D JUNGLE per rivestimenti interni ed esterni","description":"Pannelli decorativi 3D JUNGLE, sono realizzati con materiale eco compatibile innovativo, studiato appositamente dall\u2019azienda a base di","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/","og_locale":"it_IT","og_type":"article","og_title":"Pannelli decorativi 3D JUNGLE per rivestimenti interni ed esterni","og_description":"Pannelli decorativi 3D JUNGLE, sono realizzati con materiale eco compatibile innovativo, studiato appositamente dall\u2019azienda a base di","og_url":"https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/","og_site_name":"Arredareidee","article_modified_time":"2021-08-13T08:25:14+00:00","og_image":[{"width":533,"height":687,"url":"https:\/\/arredareidee.com\/wp-content\/uploads\/2021\/02\/Jungle-Decor.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/","url":"https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/","name":"Pannelli decorativi 3D JUNGLE per rivestimenti interni ed esterni","isPartOf":{"@id":"https:\/\/arredareidee.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/#primaryimage"},"image":{"@id":"https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/#primaryimage"},"thumbnailUrl":"https:\/\/arredareidee.com\/wp-content\/uploads\/2021\/02\/Jungle-Decor.jpg","datePublished":"2021-02-06T18:54:32+00:00","dateModified":"2021-08-13T08:25:14+00:00","description":"Pannelli decorativi 3D JUNGLE, sono realizzati con materiale eco compatibile innovativo, studiato appositamente dall\u2019azienda a base di","breadcrumb":{"@id":"https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/#primaryimage","url":"https:\/\/arredareidee.com\/wp-content\/uploads\/2021\/02\/Jungle-Decor.jpg","contentUrl":"https:\/\/arredareidee.com\/wp-content\/uploads\/2021\/02\/Jungle-Decor.jpg","width":533,"height":687,"caption":"Jungle Decor"},{"@type":"BreadcrumbList","@id":"https:\/\/arredareidee.com\/index.php\/product\/pannelli-decorativi-3d-jungle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arredareidee.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/arredareidee.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Pannelli decorativi 3D JUNGLE"}]},{"@type":"WebSite","@id":"https:\/\/arredareidee.com\/#website","url":"https:\/\/arredareidee.com\/","name":"Arredareidee","description":"Decorazioni personalizzate","publisher":{"@id":"https:\/\/arredareidee.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arredareidee.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/arredareidee.com\/#organization","name":"Arredareidee","url":"https:\/\/arredareidee.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/arredareidee.com\/#\/schema\/logo\/image\/","url":"https:\/\/arredareidee.com\/wp-content\/uploads\/2021\/01\/cropped-Arredareidee.png","contentUrl":"https:\/\/arredareidee.com\/wp-content\/uploads\/2021\/01\/cropped-Arredareidee.png","width":868,"height":157,"caption":"Arredareidee"},"image":{"@id":"https:\/\/arredareidee.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/arredareidee.com\/index.php\/wp-json\/wp\/v2\/product\/124142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arredareidee.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/arredareidee.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arredareidee.com\/index.php\/wp-json\/wp\/v2\/media\/124150"}],"wp:attachment":[{"href":"https:\/\/arredareidee.com\/index.php\/wp-json\/wp\/v2\/media?parent=124142"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/arredareidee.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=124142"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/arredareidee.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=124142"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/arredareidee.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=124142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}